{"id":26,"count":5,"description":"","link":"https:\/\/www.1099online.com\/blog\/category\/1099-b\/","name":"1099-B","slug":"1099-b","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>1099-B Archives - 1099Online Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.1099online.com\/blog\/category\/1099-b\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"1099-B Archives - 1099Online Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.1099online.com\/blog\/category\/1099-b\/\" \/>\n<meta property=\"og:site_name\" content=\"1099Online Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.1099online.com\/blog\/category\/1099-b\/\",\"url\":\"https:\/\/www.1099online.com\/blog\/category\/1099-b\/\",\"name\":\"1099-B Archives - 1099Online Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.1099online.com\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.1099online.com\/blog\/category\/1099-b\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.1099online.com\/blog\/category\/1099-b\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.1099online.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"1099-B\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.1099online.com\/blog\/#website\",\"url\":\"https:\/\/www.1099online.com\/blog\/\",\"name\":\"1099Online Blog\",\"description\":\"\",\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"1099-B Archives - 1099Online Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.1099online.com\/blog\/category\/1099-b\/","og_locale":"en_US","og_type":"article","og_title":"1099-B Archives - 1099Online Blog","og_url":"https:\/\/www.1099online.com\/blog\/category\/1099-b\/","og_site_name":"1099Online Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.1099online.com\/blog\/category\/1099-b\/","url":"https:\/\/www.1099online.com\/blog\/category\/1099-b\/","name":"1099-B Archives - 1099Online Blog","isPartOf":{"@id":"https:\/\/www.1099online.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.1099online.com\/blog\/category\/1099-b\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.1099online.com\/blog\/category\/1099-b\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.1099online.com\/blog\/"},{"@type":"ListItem","position":2,"name":"1099-B"}]},{"@type":"WebSite","@id":"https:\/\/www.1099online.com\/blog\/#website","url":"https:\/\/www.1099online.com\/blog\/","name":"1099Online Blog","description":"","inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.1099online.com\/blog\/wp-json\/wp\/v2\/categories\/26","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.1099online.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.1099online.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.1099online.com\/blog\/wp-json\/wp\/v2\/posts?categories=26"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}